{"id":200386,"date":"2026-08-04T10:43:25","date_gmt":"2026-08-04T08:43:25","guid":{"rendered":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/"},"modified":"2026-08-04T10:43:27","modified_gmt":"2026-08-04T08:43:27","slug":"latino-dance-mit-freddy-generationenuebergreifend","status":"publish","type":"product","link":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/","title":{"rendered":"Latino Dance mit Freddy (generationen\u00fcbergreifend)"},"excerpt":{"rendered":"<p>Lateinamerikanische Musik und verschiedene Tanzstile unter Anleitung von unserem Trainer Freddy. Bei Schlechtwetter findet die Aktivit\u00e4t im Klub statt.<\/p>\n","protected":false},"author":558,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-200386","product","type-product","status-publish","product_cat-uncategorized","first","instock","taxable","shipping-taxable","purchasable","product-type-event"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"og:description\" content=\"Lateinamerikanische Musik und verschiedene Tanzstile unter Anleitung von unserem Trainer Freddy. Bei Schlechtwetter findet die Aktivit\u00e4t im Klub statt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/\" \/>\n<meta property=\"og:site_name\" content=\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-04T08:43:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/latino-dance-mit-freddy-generationenuebergreifend\\\/\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/latino-dance-mit-freddy-generationenuebergreifend\\\/\",\"name\":\"Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\"},\"datePublished\":\"2026-08-04T08:43:25+00:00\",\"dateModified\":\"2026-08-04T08:43:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/latino-dance-mit-freddy-generationenuebergreifend\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/latino-dance-mit-freddy-generationenuebergreifend\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/latino-dance-mit-freddy-generationenuebergreifend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Latino Dance mit Freddy (generationen\u00fcbergreifend)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\",\"name\":\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"description\":\"Unsere Angebote der H\u00e4user und Klubs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/","og_locale":"de_DE","og_type":"article","og_title":"Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","og_description":"Lateinamerikanische Musik und verschiedene Tanzstile unter Anleitung von unserem Trainer Freddy. Bei Schlechtwetter findet die Aktivit\u00e4t im Klub statt.","og_url":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/","og_site_name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","article_modified_time":"2026-08-04T08:43:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/","url":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/","name":"Latino Dance mit Freddy (generationen\u00fcbergreifend) - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","isPartOf":{"@id":"https:\/\/kwp.at\/veranstaltungen\/#website"},"datePublished":"2026-08-04T08:43:25+00:00","dateModified":"2026-08-04T08:43:27+00:00","breadcrumb":{"@id":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/latino-dance-mit-freddy-generationenuebergreifend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Latino Dance mit Freddy (generationen\u00fcbergreifend)"}]},{"@type":"WebSite","@id":"https:\/\/kwp.at\/veranstaltungen\/#website","url":"https:\/\/kwp.at\/veranstaltungen\/","name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","description":"Unsere Angebote der H\u00e4user und Klubs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kwp.at\/veranstaltungen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product\/200386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/users\/558"}],"replies":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/comments?post=200386"}],"wp:attachment":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/media?parent=200386"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_brand?post=200386"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_cat?post=200386"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_tag?post=200386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}