{"id":197822,"date":"2026-07-03T14:46:13","date_gmt":"2026-07-03T12:46:13","guid":{"rendered":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/"},"modified":"2026-07-03T14:46:14","modified_gmt":"2026-07-03T12:46:14","slug":"verschiedene-taenze-mit-lie-25","status":"publish","type":"product","link":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/","title":{"rendered":"Verschiedene T\u00e4nze mit Lie"},"excerpt":{"rendered":"<p>Musik und Tanz<\/p>\n","protected":false},"author":668,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-197822","product","type-product","status-publish","product_cat-uncategorized","first","instock","taxable","shipping-taxable","purchasable","product-type-event"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"og:description\" content=\"Musik und Tanz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T12:46:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/verschiedene-taenze-mit-lie-25\\\/\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/verschiedene-taenze-mit-lie-25\\\/\",\"name\":\"Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\"},\"datePublished\":\"2026-07-03T12:46:13+00:00\",\"dateModified\":\"2026-07-03T12:46:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/verschiedene-taenze-mit-lie-25\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/verschiedene-taenze-mit-lie-25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/verschiedene-taenze-mit-lie-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verschiedene T\u00e4nze mit Lie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\",\"name\":\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"description\":\"Unsere Angebote der H\u00e4user und Klubs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/","og_locale":"de_DE","og_type":"article","og_title":"Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","og_description":"Musik und Tanz","og_url":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/","og_site_name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","article_modified_time":"2026-07-03T12:46:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/","url":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/","name":"Verschiedene T\u00e4nze mit Lie - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","isPartOf":{"@id":"https:\/\/kwp.at\/veranstaltungen\/#website"},"datePublished":"2026-07-03T12:46:13+00:00","dateModified":"2026-07-03T12:46:14+00:00","breadcrumb":{"@id":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/verschiedene-taenze-mit-lie-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Verschiedene T\u00e4nze mit Lie"}]},{"@type":"WebSite","@id":"https:\/\/kwp.at\/veranstaltungen\/#website","url":"https:\/\/kwp.at\/veranstaltungen\/","name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","description":"Unsere Angebote der H\u00e4user und Klubs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kwp.at\/veranstaltungen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product\/197822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/users\/668"}],"replies":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/comments?post=197822"}],"wp:attachment":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/media?parent=197822"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_brand?post=197822"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_cat?post=197822"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_tag?post=197822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}