{"id":191487,"date":"2026-06-02T11:17:10","date_gmt":"2026-06-02T09:17:10","guid":{"rendered":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/"},"modified":"2026-06-02T11:17:11","modified_gmt":"2026-06-02T09:17:11","slug":"seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4","status":"publish","type":"product","link":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/","title":{"rendered":"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag"},"excerpt":{"rendered":"<p>Einfach zur Abfahrtsstelle kommen und mitfahren: <b>1130, Hietzinger Platzl, vor der Polizeistation\/Kirche<\/b>  <br \/> Der Fahrtkostenbeitrag f\u00fcr diesen Halbtagesausflug betr\u00e4gt 10 Euro. Keine Anmeldung notwendig! Sie k\u00f6nnen direkt im Bus eine Einzelfahrkarte erwerben. Bitte halten Sie daf\u00fcr das Entgeld abgez\u00e4hlt bereit. <br \/>Die Konsumationen am Zielort sind selbst zu bezahlen. <br \/> Bitte um Verst\u00e4ndnis: Wir behalten uns vor, bei weniger als 10 zahlenden Personen die Fahrt kurzfristig abzusagen. In F\u00e4llen von h\u00f6herer Gewalt kann das Fahrtziel kurz vor Abfahrt ge\u00e4ndert werden. <\/p>\n<h4>Wr. Neustadt \u2013 freier Nachmittag<\/h4>\n<p>Wie w\u00e4re es mit einem Ausflug nach Wiener Neustadt? Die historische Stadt bietet eine reiche Geschichte, beeindruckende Architektur und gem\u00fctliche Kaffeeh\u00e4user. Besuchen Sie den Dom, die Milit\u00e4rakademie und das Stadtmuseum. Genie\u00dfen Sie entspannte Spazierg\u00e4nge und kulturelle Highlights in einer charmanten Umgebung.<\/p>\n","protected":false},"author":79,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-191487","product","type-product","status-publish","product_cat-uncategorized","first","instock","taxable","shipping-taxable","purchasable","product-type-event"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"og:description\" content=\"Einfach zur Abfahrtsstelle kommen und mitfahren: 1130, Hietzinger Platzl, vor der Polizeistation\/Kirche  Der Fahrtkostenbeitrag f\u00fcr diesen Halbtagesausflug betr\u00e4gt 10 Euro. Keine Anmeldung notwendig! Sie k\u00f6nnen direkt im Bus eine Einzelfahrkarte erwerben. Bitte halten Sie daf\u00fcr das Entgeld abgez\u00e4hlt bereit. Die Konsumationen am Zielort sind selbst zu bezahlen. Bitte um Verst\u00e4ndnis: Wir behalten uns vor, bei weniger als 10 zahlenden Personen die Fahrt kurzfristig abzusagen. In F\u00e4llen von h\u00f6herer Gewalt kann das Fahrtziel kurz vor Abfahrt ge\u00e4ndert werden. Wr. Neustadt \u2013 freier NachmittagWie w\u00e4re es mit einem Ausflug nach Wiener Neustadt? Die historische Stadt bietet eine reiche Geschichte, beeindruckende Architektur und gem\u00fctliche Kaffeeh\u00e4user. Besuchen Sie den Dom, die Milit\u00e4rakademie und das Stadtmuseum. Genie\u00dfen Sie entspannte Spazierg\u00e4nge und kulturelle Highlights in einer charmanten Umgebung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T09:17:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\\\/\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\\\/\",\"name\":\"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\"},\"datePublished\":\"2026-06-02T09:17:10+00:00\",\"dateModified\":\"2026-06-02T09:17:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\",\"name\":\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"description\":\"Unsere Angebote der H\u00e4user und Klubs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/","og_locale":"de_DE","og_type":"article","og_title":"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","og_description":"Einfach zur Abfahrtsstelle kommen und mitfahren: 1130, Hietzinger Platzl, vor der Polizeistation\/Kirche  Der Fahrtkostenbeitrag f\u00fcr diesen Halbtagesausflug betr\u00e4gt 10 Euro. Keine Anmeldung notwendig! Sie k\u00f6nnen direkt im Bus eine Einzelfahrkarte erwerben. Bitte halten Sie daf\u00fcr das Entgeld abgez\u00e4hlt bereit. Die Konsumationen am Zielort sind selbst zu bezahlen. Bitte um Verst\u00e4ndnis: Wir behalten uns vor, bei weniger als 10 zahlenden Personen die Fahrt kurzfristig abzusagen. In F\u00e4llen von h\u00f6herer Gewalt kann das Fahrtziel kurz vor Abfahrt ge\u00e4ndert werden. Wr. Neustadt \u2013 freier NachmittagWie w\u00e4re es mit einem Ausflug nach Wiener Neustadt? Die historische Stadt bietet eine reiche Geschichte, beeindruckende Architektur und gem\u00fctliche Kaffeeh\u00e4user. Besuchen Sie den Dom, die Milit\u00e4rakademie und das Stadtmuseum. Genie\u00dfen Sie entspannte Spazierg\u00e4nge und kulturelle Highlights in einer charmanten Umgebung.","og_url":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/","og_site_name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","article_modified_time":"2026-06-02T09:17:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/","url":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/","name":"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","isPartOf":{"@id":"https:\/\/kwp.at\/veranstaltungen\/#website"},"datePublished":"2026-06-02T09:17:10+00:00","dateModified":"2026-06-02T09:17:11+00:00","breadcrumb":{"@id":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/seniorinnen-unterwegs-nach-wr-neustadt-freier-nachmittag-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Senior*innen unterwegs nach Wr. Neustadt \u2013 freier Nachmittag"}]},{"@type":"WebSite","@id":"https:\/\/kwp.at\/veranstaltungen\/#website","url":"https:\/\/kwp.at\/veranstaltungen\/","name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","description":"Unsere Angebote der H\u00e4user und Klubs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kwp.at\/veranstaltungen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product\/191487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/comments?post=191487"}],"wp:attachment":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/media?parent=191487"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_brand?post=191487"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_cat?post=191487"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_tag?post=191487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}