{"id":188848,"date":"2026-05-11T16:02:17","date_gmt":"2026-05-11T14:02:17","guid":{"rendered":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/"},"modified":"2026-05-11T16:02:18","modified_gmt":"2026-05-11T14:02:18","slug":"herstory-frauen-erzaehlen-ihr-leben-5","status":"publish","type":"product","link":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/","title":{"rendered":"HERStory: Frauen erz\u00e4hlen ihr Leben"},"excerpt":{"rendered":"<p>Ihr seid Zeitzeuginnen privater und gesellschaftlicher Ver\u00e4nderungen. Mich interessiert euer Alltag, welchen Herausforderungen ihr begegnet seid und wie ihr sie gemeistert habt. Ein Erz\u00e4hlkreis nur f\u00fcr Frauen.<\/p>\n","protected":false},"author":778,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-188848","1":"product","2":"type-product","3":"status-publish","5":"product_cat-uncategorized","7":"first","8":"instock","9":"taxable","10":"shipping-taxable","11":"purchasable","12":"product-type-event"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"og:description\" content=\"Ihr seid Zeitzeuginnen privater und gesellschaftlicher Ver\u00e4nderungen. Mich interessiert euer Alltag, welchen Herausforderungen ihr begegnet seid und wie ihr sie gemeistert habt. Ein Erz\u00e4hlkreis nur f\u00fcr Frauen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T14:02:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/herstory-frauen-erzaehlen-ihr-leben-5\\\/\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/herstory-frauen-erzaehlen-ihr-leben-5\\\/\",\"name\":\"HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\"},\"datePublished\":\"2026-05-11T14:02:17+00:00\",\"dateModified\":\"2026-05-11T14:02:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/herstory-frauen-erzaehlen-ihr-leben-5\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/herstory-frauen-erzaehlen-ihr-leben-5\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/product\\\/herstory-frauen-erzaehlen-ihr-leben-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HERStory: Frauen erz\u00e4hlen ihr Leben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/#website\",\"url\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/\",\"name\":\"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs\",\"description\":\"Unsere Angebote der H\u00e4user und Klubs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kwp.at\\\/veranstaltungen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/","og_locale":"de_DE","og_type":"article","og_title":"HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","og_description":"Ihr seid Zeitzeuginnen privater und gesellschaftlicher Ver\u00e4nderungen. Mich interessiert euer Alltag, welchen Herausforderungen ihr begegnet seid und wie ihr sie gemeistert habt. Ein Erz\u00e4hlkreis nur f\u00fcr Frauen.","og_url":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/","og_site_name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","article_modified_time":"2026-05-11T14:02:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/","url":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/","name":"HERStory: Frauen erz\u00e4hlen ihr Leben - Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","isPartOf":{"@id":"https:\/\/kwp.at\/veranstaltungen\/#website"},"datePublished":"2026-05-11T14:02:17+00:00","dateModified":"2026-05-11T14:02:18+00:00","breadcrumb":{"@id":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kwp.at\/veranstaltungen\/product\/herstory-frauen-erzaehlen-ihr-leben-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/kwp.at\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"HERStory: Frauen erz\u00e4hlen ihr Leben"}]},{"@type":"WebSite","@id":"https:\/\/kwp.at\/veranstaltungen\/#website","url":"https:\/\/kwp.at\/veranstaltungen\/","name":"Veranstaltungen - H\u00e4user zum Leben und Pensionist*innenklubs","description":"Unsere Angebote der H\u00e4user und Klubs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kwp.at\/veranstaltungen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product\/188848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/users\/778"}],"replies":[{"embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/comments?post=188848"}],"wp:attachment":[{"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/media?parent=188848"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_brand?post=188848"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_cat?post=188848"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kwp.at\/veranstaltungen\/wp-json\/wp\/v2\/product_tag?post=188848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}